{"id":4784,"date":"2022-10-19T16:54:18","date_gmt":"2022-10-19T16:54:18","guid":{"rendered":"https:\/\/www.5milamarche.com\/?p=4784"},"modified":"2022-10-19T16:54:20","modified_gmt":"2022-10-19T16:54:20","slug":"in-15-mila-a-porto-recanati-la-5-mila-marche-e-una-festa","status":"publish","type":"post","link":"https:\/\/www.5milamarche.com\/en\/news\/in-15-mila-a-porto-recanati-la-5-mila-marche-e-una-festa\/","title":{"rendered":"In 15 mila a Porto Recanati: la 5 Mila Marche \u00e8 una festa"},"content":{"rendered":"<p><em>La GF 5 Mila ha messo fine al weekend all\u2019insegna della bicicletta e della scoperta della Regione. Tutto il territorio \u00e8 stato coinvolto dalla 3 giorni di eventi, con hotel al completo e appassionati da ogni parte del mondo<\/em><\/p>\n\n\n\n<p><em>\u201cPronti a farvi emozionare\u201d<\/em> era il leit motiv dell\u2019edizione di quest\u2019anno della <strong>5 Mila Marche<\/strong>. E cos\u00ec \u00e8 stato. I numeri della 3 giorni di eventi che facevano base a <strong>Porto Recanati (MC)<\/strong>, ma coinvolgevano buona parte del territorio marchigiano, parlano di una missione compiuta per coinvolgimento e interesse generale attorno alla manifestazione.<\/p>\n\n\n\n<p>Le presenze registrate nel weekend toccano le <strong>15 mila<\/strong>, con appassionati giunti da tutta Italia ma anche dall\u2019estero. A Porto Recanati sono infatti arrivati ciclisti da <strong>38 province italiane<\/strong>, con una folta rappresentanza di lombardi, emiliano-romagnoli, trentini e altoatesini, e da ben <strong>15 Nazioni europee e non<\/strong>, vale a dire Gran Bretagna, Svizzera, Germania, Danimarca, Austria, Spagna, Svizzera, Francia, Repubblica Ceca, Russia, Bielorussia, Irlanda e Brasile.<\/p>\n\n\n\n<p>Tra staff e volontari sono state ben <strong>650 <\/strong>le persone coinvolte nell\u2019organizzazione dei vari eventi e iniziative del weekend, con <strong>268 <\/strong>di questi impegnati nel presidio degli incroci, sempre delicati quando si parla di una manifestazione ciclistica. <em>&#8220;Innanzitutto, mi preme ringraziare volontari, sponsor, enti e comuni che si sono spesi insieme a noi per organizzare questi 3 giorni della 5 Mila Marche<\/em> \u2013 ha spiegato <strong>l\u2019organizzatore Andrea Tonti<\/strong> -. <em>Io ci metto la faccio, ma senza di loro sarebbe impossibile poter tirare su una manifestazione come questa. I numeri ci dicono che stiamo andando nella direzione giusta: le Marche, dal punto di vista cicloturistico, sono sempre pi\u00f9 un punto di riferimento per gli appassionati e sono contento che anche a livello istituzionale si considerino eventi come questi un&#8217;opportunit\u00e0 per crescere. L&#8217;edizione di quest&#8217;anno \u00e8 stata importante per consolidare il marchio: vogliamo che sempre pi\u00f9 appassionati e turisti dall\u2019Italia e dall\u2019estero vengano nelle Marche per pedalare e scoprire la Regione nella sua interezza, dal mare ai Monti Sibillini&#8221;.<\/em><\/p>\n\n\n\n<p><em>\u201cBasta leggere i numeri per comprendere l&#8217;indotto che porta un evento come questo<\/em> &#8211; \u00e8 stato invece il commento del <strong>Sindaco di Porto Recanati, Andrea Michelini<\/strong> -. <em>La 5 Mila Marche \u00e8 anche un grande spot per la destagionalizzazione, perch\u00e9 ti permette di allungare il periodo migliore del turismo per qualche settimana. Con gli eventi sportivi e la bicicletta \u00e8 possibile riempire una cittadina di mare anche ad ottobre, a maggior ragione se le giornate sono splendide come lo sono state in questi giorni\u201d.<\/em><\/p>\n\n\n\n<p>La 5 Mila Marche \u00e8 anche l\u2019unico evento facente parte del prestigioso circuito<strong> Granfondo WorldTour<\/strong>, che raccoglie i migliori eventi di questo genere a livello internazionale. <em>&#8220;Questo \u00e8 un evento giovane che sta crescendo anno dopo anno<\/em> \u2013 ha detto il catalano <strong>Dani Buyo<\/strong>, <strong>CEO di Granfondo WorldTour<\/strong>, ospite della tre giorni marchigiana -. <em>\u00c8 bello vedere come lavorano Andrea Tonti e la sua squadra, l\u2019entusiasmo che c\u2019\u00e8 attorno alla manifestazione e il grande supporto che danno sponsor e Istituzioni. Questo evento racchiude perfettamente tutte le caratteristiche che servono per appartenere al WorldTour. Il percorso \u00e8 tra i pi\u00f9 duri d&#8217;Europa e turisticamente \u00e8 eccezionale\u201d.<\/em><\/p>\n\n\n\n<p>A chiudere la 5 Mila Marche \u00e8 stata la <strong>GF 5 Mila<\/strong>. Chi ha scelto il percorso lungo, si \u00e8 dovuto testare su 113 km e 1720 metri di dislivello, caratterizzati da scenari meravigliosi tipici dell\u2019entroterra marchigiano, con tantissimi saliscendi che hanno reso la corsa davvero dura per tutti. Per chi ha affrontato il percorso medio, invece, sono stati 82 i km da affrontare, con 1220 metri di dislivello complessivo.<\/p>\n\n\n\n<p>Ad imporsi nel percorso lungo \u00e8 stato <strong>Marco Oliva<\/strong> (A&amp;G), bravo a resistere al ritorno del gruppo, regolato da Pietro Dutto (Team Mentecorpo) sull\u2019ex professionista Paolo Tot\u00f2. Tra le donne ha vinto in solitaria <strong>Maria Elena Palmisano<\/strong> (Garda Scott Matergia), anticipando Emilie Bottini (Zerotest) e Piera Bertorelli (Team Go Fast).<\/p>\n\n\n\n<p>Nel medio invece si impone in uno sprint ristretto <strong>Marco Mordini<\/strong> (Argon 18-Hicari-Stemax) su Manuel Fedele (Team Go Fast) e Giulio Scopetani (Vitam-in), mentre al femminile si impone <strong>Lisa De Cesare<\/strong> (Highroad), con Luisa Isonni (Boario) seconda e Mara Manfredi (Vivo -MG.K Vis-Dal Colle) terza.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"4790\" src=\"https:\/\/www.5milamarche.com\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-10-16-at-16.49.00.jpeg\" alt=\"\" class=\"wp-image-4790\" srcset=\"https:\/\/www.5milamarche.com\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-10-16-at-16.49.00.jpeg 1024w, https:\/\/www.5milamarche.com\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-10-16-at-16.49.00-600x400.jpeg 600w, https:\/\/www.5milamarche.com\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-10-16-at-16.49.00-300x200.jpeg 300w, https:\/\/www.5milamarche.com\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-10-16-at-16.49.00-768x512.jpeg 768w, https:\/\/www.5milamarche.com\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-10-16-at-16.49.00-18x12.jpeg 18w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"4789\" src=\"https:\/\/www.5milamarche.com\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-10-16-at-16.49.00-1.jpeg\" alt=\"\" class=\"wp-image-4789\" srcset=\"https:\/\/www.5milamarche.com\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-10-16-at-16.49.00-1.jpeg 1024w, https:\/\/www.5milamarche.com\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-10-16-at-16.49.00-1-600x400.jpeg 600w, https:\/\/www.5milamarche.com\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-10-16-at-16.49.00-1-300x200.jpeg 300w, https:\/\/www.5milamarche.com\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-10-16-at-16.49.00-1-768x512.jpeg 768w, https:\/\/www.5milamarche.com\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-10-16-at-16.49.00-1-18x12.jpeg 18w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"4787\" src=\"https:\/\/www.5milamarche.com\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-10-16-at-16.49.01.jpeg\" alt=\"\" class=\"wp-image-4787\" srcset=\"https:\/\/www.5milamarche.com\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-10-16-at-16.49.01.jpeg 1024w, https:\/\/www.5milamarche.com\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-10-16-at-16.49.01-600x400.jpeg 600w, https:\/\/www.5milamarche.com\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-10-16-at-16.49.01-300x200.jpeg 300w, https:\/\/www.5milamarche.com\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-10-16-at-16.49.01-768x512.jpeg 768w, https:\/\/www.5milamarche.com\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-10-16-at-16.49.01-18x12.jpeg 18w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"4786\" src=\"https:\/\/www.5milamarche.com\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-10-16-at-16.49.01-1.jpeg\" alt=\"\" class=\"wp-image-4786\" srcset=\"https:\/\/www.5milamarche.com\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-10-16-at-16.49.01-1.jpeg 1024w, https:\/\/www.5milamarche.com\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-10-16-at-16.49.01-1-600x400.jpeg 600w, https:\/\/www.5milamarche.com\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-10-16-at-16.49.01-1-300x200.jpeg 300w, https:\/\/www.5milamarche.com\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-10-16-at-16.49.01-1-768x512.jpeg 768w, https:\/\/www.5milamarche.com\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-10-16-at-16.49.01-1-18x12.jpeg 18w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"4785\" src=\"https:\/\/www.5milamarche.com\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-10-16-at-16.49.00-3.jpeg\" alt=\"\" class=\"wp-image-4785\" srcset=\"https:\/\/www.5milamarche.com\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-10-16-at-16.49.00-3.jpeg 1024w, https:\/\/www.5milamarche.com\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-10-16-at-16.49.00-3-600x400.jpeg 600w, https:\/\/www.5milamarche.com\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-10-16-at-16.49.00-3-300x200.jpeg 300w, https:\/\/www.5milamarche.com\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-10-16-at-16.49.00-3-768x512.jpeg 768w, https:\/\/www.5milamarche.com\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-10-16-at-16.49.00-3-18x12.jpeg 18w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>","protected":false},"excerpt":{"rendered":"<p>La GF 5 Mila ha messo fine al weekend all\u2019insegna della bicicletta e della scoperta della Regione. Tutto il territorio \u00e8 stato coinvolto dalla 3 giorni di eventi, con hotel al completo e appassionati da ogni parte del mondo \u201cPronti a farvi emozionare\u201d era il leit motiv dell\u2019edizione di quest\u2019anno della 5 Mila Marche. E [&hellip;]<\/p>","protected":false},"author":4,"featured_media":4788,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[10],"tags":[17,29,18],"class_list":["post-4784","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-5-mila-marche","tag-porto-recanati","tag-successo"],"_links":{"self":[{"href":"https:\/\/www.5milamarche.com\/en\/wp-json\/wp\/v2\/posts\/4784","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.5milamarche.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.5milamarche.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.5milamarche.com\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.5milamarche.com\/en\/wp-json\/wp\/v2\/comments?post=4784"}],"version-history":[{"count":1,"href":"https:\/\/www.5milamarche.com\/en\/wp-json\/wp\/v2\/posts\/4784\/revisions"}],"predecessor-version":[{"id":4791,"href":"https:\/\/www.5milamarche.com\/en\/wp-json\/wp\/v2\/posts\/4784\/revisions\/4791"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.5milamarche.com\/en\/wp-json\/wp\/v2\/media\/4788"}],"wp:attachment":[{"href":"https:\/\/www.5milamarche.com\/en\/wp-json\/wp\/v2\/media?parent=4784"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.5milamarche.com\/en\/wp-json\/wp\/v2\/categories?post=4784"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.5milamarche.com\/en\/wp-json\/wp\/v2\/tags?post=4784"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}